{"id":200,"count":5,"description":"","link":"http:\/\/genuinewines.com\/en\/blog\/tag\/delphine-brulez\/","name":"Delphine Brulez","slug":"delphine-brulez","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Delphine Brulez Archives &#8226; Genuine Wines<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/genuinewines.com\/en\/blog\/tag\/delphine-brulez\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Delphine Brulez Archives &#8226; Genuine Wines\" \/>\n<meta property=\"og:url\" content=\"http:\/\/genuinewines.com\/en\/blog\/tag\/delphine-brulez\/\" \/>\n<meta property=\"og:site_name\" content=\"Genuine Wines\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\\\/\\\/genuinewines.com\\\/en\\\/blog\\\/tag\\\/delphine-brulez\\\/\",\"url\":\"http:\\\/\\\/genuinewines.com\\\/en\\\/blog\\\/tag\\\/delphine-brulez\\\/\",\"name\":\"Delphine Brulez Archives &#8226; Genuine Wines\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/genuinewines.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/genuinewines.com\\\/en\\\/blog\\\/tag\\\/delphine-brulez\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/genuinewines.com\\\/en\\\/blog\\\/tag\\\/delphine-brulez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/genuinewines.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Delphine Brulez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/genuinewines.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/genuinewines.com\\\/en\\\/\",\"name\":\"Genuine Wines\",\"description\":\"English language version of Genuine Wines website\",\"publisher\":{\"@id\":\"https:\\\/\\\/genuinewines.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/genuinewines.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/genuinewines.com\\\/en\\\/#organization\",\"name\":\"Genuine Wines\",\"url\":\"https:\\\/\\\/genuinewines.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/genuinewines.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/genuinewines.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/09\\\/Logo_noir_GenuineWines.svg\",\"contentUrl\":\"http:\\\/\\\/genuinewines.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/09\\\/Logo_noir_GenuineWines.svg\",\"caption\":\"Genuine Wines\"},\"image\":{\"@id\":\"https:\\\/\\\/genuinewines.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GenuineWines\\\/\",\"https:\\\/\\\/www.instagram.com\\\/genuinewines\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/27114733\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Delphine Brulez Archives &#8226; Genuine Wines","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/genuinewines.com\/en\/blog\/tag\/delphine-brulez\/","og_locale":"en_GB","og_type":"article","og_title":"Delphine Brulez Archives &#8226; Genuine Wines","og_url":"http:\/\/genuinewines.com\/en\/blog\/tag\/delphine-brulez\/","og_site_name":"Genuine Wines","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/genuinewines.com\/en\/blog\/tag\/delphine-brulez\/","url":"http:\/\/genuinewines.com\/en\/blog\/tag\/delphine-brulez\/","name":"Delphine Brulez Archives &#8226; Genuine Wines","isPartOf":{"@id":"https:\/\/genuinewines.com\/en\/#website"},"breadcrumb":{"@id":"http:\/\/genuinewines.com\/en\/blog\/tag\/delphine-brulez\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"http:\/\/genuinewines.com\/en\/blog\/tag\/delphine-brulez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/genuinewines.com\/en\/"},{"@type":"ListItem","position":2,"name":"Delphine Brulez"}]},{"@type":"WebSite","@id":"https:\/\/genuinewines.com\/en\/#website","url":"https:\/\/genuinewines.com\/en\/","name":"Genuine Wines","description":"English language version of Genuine Wines website","publisher":{"@id":"https:\/\/genuinewines.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/genuinewines.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/genuinewines.com\/en\/#organization","name":"Genuine Wines","url":"https:\/\/genuinewines.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/genuinewines.com\/en\/#\/schema\/logo\/image\/","url":"http:\/\/genuinewines.com\/en\/wp-content\/uploads\/sites\/3\/2025\/09\/Logo_noir_GenuineWines.svg","contentUrl":"http:\/\/genuinewines.com\/en\/wp-content\/uploads\/sites\/3\/2025\/09\/Logo_noir_GenuineWines.svg","caption":"Genuine Wines"},"image":{"@id":"https:\/\/genuinewines.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GenuineWines\/","https:\/\/www.instagram.com\/genuinewines\/","https:\/\/www.linkedin.com\/company\/27114733\/"]}]}},"_links":{"self":[{"href":"http:\/\/genuinewines.com\/en\/wp-json\/wp\/v2\/tags\/200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/genuinewines.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/genuinewines.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/genuinewines.com\/en\/wp-json\/wp\/v2\/posts?tags=200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}