{"id":4989,"date":"2021-11-15T18:46:07","date_gmt":"2021-11-15T17:46:07","guid":{"rendered":"https:\/\/genuinewines.com\/en\/wp-content\/uploads\/sites\/3\/2021\/11\/26-copie-2-1.jpg"},"modified":"2021-11-15T18:46:07","modified_gmt":"2021-11-15T17:46:07","slug":"26-copie-2-1","status":"inherit","type":"attachment","link":"http:\/\/genuinewines.com\/en\/domaines\/homs-organic-minervois\/26-copie-2-1\/","title":{"rendered":"26 &#8211; copie 2-1"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"csbAdvScrollBarCursor":"","ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":""},"class_list":["post-4989","attachment","type-attachment","status-inherit","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>26 - copie 2-1 &#8226; Genuine Wines<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/genuinewines.com\/en\/wp-content\/uploads\/sites\/3\/2021\/11\/26-copie-2-1.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"26 - copie 2-1 &#8226; Genuine Wines\" \/>\n<meta property=\"og:url\" content=\"http:\/\/genuinewines.com\/en\/wp-content\/uploads\/sites\/3\/2021\/11\/26-copie-2-1.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Genuine Wines\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GenuineWines\/\" \/>\n<meta property=\"og:image\" content=\"http:\/\/genuinewines.com\/en\/wp-content\/uploads\/sites\/3\/2021\/11\/26-copie-2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"393\" \/>\n\t<meta property=\"og:image:height\" content=\"589\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/genuinewines.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/11\\\/26-copie-2-1.jpg\",\"url\":\"http:\\\/\\\/genuinewines.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/11\\\/26-copie-2-1.jpg\",\"name\":\"26 - copie 2-1 &#8226; Genuine Wines\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/genuinewines.com\\\/en\\\/#website\"},\"datePublished\":\"2021-11-15T17:46:07+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/genuinewines.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/11\\\/26-copie-2-1.jpg#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/genuinewines.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/11\\\/26-copie-2-1.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/genuinewines.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/11\\\/26-copie-2-1.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/genuinewines.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"French and Italian Estates\",\"item\":\"http:\\\/\\\/genuinewines.com\\\/en\\\/domaines\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Domaine des Homs &#8211; Minervois\",\"item\":\"https:\\\/\\\/genuinewines.com\\\/en\\\/domaines\\\/homs-organic-minervois\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"26 &#8211; copie 2-1\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/genuinewines.com\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/genuinewines.com\\\/en\\\/\",\"name\":\"Genuine Wines\",\"description\":\"English language version of Genuine Wines website\",\"publisher\":{\"@id\":\"http:\\\/\\\/genuinewines.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/genuinewines.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/genuinewines.com\\\/en\\\/#organization\",\"name\":\"Genuine Wines\",\"url\":\"http:\\\/\\\/genuinewines.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"http:\\\/\\\/genuinewines.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/genuinewines.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/09\\\/Logo_noir_GenuineWines.svg\",\"contentUrl\":\"http:\\\/\\\/genuinewines.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/09\\\/Logo_noir_GenuineWines.svg\",\"caption\":\"Genuine Wines\"},\"image\":{\"@id\":\"http:\\\/\\\/genuinewines.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GenuineWines\\\/\",\"https:\\\/\\\/www.instagram.com\\\/genuinewines\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/27114733\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"26 - copie 2-1 &#8226; Genuine Wines","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/genuinewines.com\/en\/wp-content\/uploads\/sites\/3\/2021\/11\/26-copie-2-1.jpg","og_locale":"en_GB","og_type":"article","og_title":"26 - copie 2-1 &#8226; Genuine Wines","og_url":"http:\/\/genuinewines.com\/en\/wp-content\/uploads\/sites\/3\/2021\/11\/26-copie-2-1.jpg","og_site_name":"Genuine Wines","article_publisher":"https:\/\/www.facebook.com\/GenuineWines\/","og_image":[{"width":393,"height":589,"url":"http:\/\/genuinewines.com\/en\/wp-content\/uploads\/sites\/3\/2021\/11\/26-copie-2-1.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/genuinewines.com\/en\/wp-content\/uploads\/sites\/3\/2021\/11\/26-copie-2-1.jpg","url":"http:\/\/genuinewines.com\/en\/wp-content\/uploads\/sites\/3\/2021\/11\/26-copie-2-1.jpg","name":"26 - copie 2-1 &#8226; Genuine Wines","isPartOf":{"@id":"http:\/\/genuinewines.com\/en\/#website"},"datePublished":"2021-11-15T17:46:07+00:00","breadcrumb":{"@id":"http:\/\/genuinewines.com\/en\/wp-content\/uploads\/sites\/3\/2021\/11\/26-copie-2-1.jpg#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["http:\/\/genuinewines.com\/en\/wp-content\/uploads\/sites\/3\/2021\/11\/26-copie-2-1.jpg"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/genuinewines.com\/en\/wp-content\/uploads\/sites\/3\/2021\/11\/26-copie-2-1.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/genuinewines.com\/en\/"},{"@type":"ListItem","position":2,"name":"French and Italian Estates","item":"http:\/\/genuinewines.com\/en\/domaines\/"},{"@type":"ListItem","position":3,"name":"Domaine des Homs &#8211; Minervois","item":"https:\/\/genuinewines.com\/en\/domaines\/homs-organic-minervois\/"},{"@type":"ListItem","position":4,"name":"26 &#8211; copie 2-1"}]},{"@type":"WebSite","@id":"http:\/\/genuinewines.com\/en\/#website","url":"http:\/\/genuinewines.com\/en\/","name":"Genuine Wines","description":"English language version of Genuine Wines website","publisher":{"@id":"http:\/\/genuinewines.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/genuinewines.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"http:\/\/genuinewines.com\/en\/#organization","name":"Genuine Wines","url":"http:\/\/genuinewines.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"http:\/\/genuinewines.com\/en\/#\/schema\/logo\/image\/","url":"http:\/\/genuinewines.com\/en\/wp-content\/uploads\/sites\/3\/2025\/09\/Logo_noir_GenuineWines.svg","contentUrl":"http:\/\/genuinewines.com\/en\/wp-content\/uploads\/sites\/3\/2025\/09\/Logo_noir_GenuineWines.svg","caption":"Genuine Wines"},"image":{"@id":"http:\/\/genuinewines.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GenuineWines\/","https:\/\/www.instagram.com\/genuinewines\/","https:\/\/www.linkedin.com\/company\/27114733\/"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/genuinewines.com\/en\/wp-content\/uploads\/sites\/3\/2021\/11\/26-copie-2-1.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"200\" height=\"300\" src=\"http:\/\/genuinewines.com\/en\/wp-content\/uploads\/sites\/3\/2021\/11\/26-copie-2-1-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"http:\/\/genuinewines.com\/en\/wp-content\/uploads\/sites\/3\/2021\/11\/26-copie-2-1-200x300.jpg 200w, http:\/\/genuinewines.com\/en\/wp-content\/uploads\/sites\/3\/2021\/11\/26-copie-2-1.jpg 393w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":393,"height":589,"file":"2021\/11\/26-copie-2-1.jpg","sizes":{"medium":{"file":"26-copie-2-1-200x300.jpg","width":200,"height":300,"mime_type":"image\/jpeg","source_url":"http:\/\/genuinewines.com\/en\/wp-content\/uploads\/sites\/3\/2021\/11\/26-copie-2-1-200x300.jpg"},"thumbnail":{"file":"26-copie-2-1-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"http:\/\/genuinewines.com\/en\/wp-content\/uploads\/sites\/3\/2021\/11\/26-copie-2-1-150x150.jpg"},"full":{"file":"26-copie-2-1.jpg","width":393,"height":589,"mime_type":"image\/jpeg","source_url":"http:\/\/genuinewines.com\/en\/wp-content\/uploads\/sites\/3\/2021\/11\/26-copie-2-1.jpg"}},"image_meta":{"aperture":"9","credit":"","camera":"Canon EOS 350D DIGITAL","caption":"","created_timestamp":"1148466868","copyright":"","focal_length":"70","iso":"320","shutter_speed":"0.002","title":"","orientation":"1","keywords":[]}},"post":598,"source_url":"http:\/\/genuinewines.com\/en\/wp-content\/uploads\/sites\/3\/2021\/11\/26-copie-2-1.jpg","filename":"26-copie-2-1.jpg","filesize":507588,"_links":{"self":[{"href":"http:\/\/genuinewines.com\/en\/wp-json\/wp\/v2\/media\/4989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/genuinewines.com\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/genuinewines.com\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/genuinewines.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/genuinewines.com\/en\/wp-json\/wp\/v2\/comments?post=4989"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":598,"href":"http:\/\/genuinewines.com\/en\/wp-json\/wp\/v2\/pages\/598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}